{"id":7921,"date":"2024-05-09T13:11:45","date_gmt":"2024-05-09T17:11:45","guid":{"rendered":"https:\/\/www.ascentria.org\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\/"},"modified":"2024-06-24T12:35:13","modified_gmt":"2024-06-24T16:35:13","slug":"la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres","status":"publish","type":"post","link":"https:\/\/www.ascentria.org\/es\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\/","title":{"rendered":"La crisis de la vivienda en EE.UU. es una cuesti\u00f3n de mujeres"},"content":{"rendered":"\n<p><strong>\u00bfCu\u00e1l es la situaci\u00f3n actual de la desigualdad en la vivienda en Estados Unidos?<\/strong><\/p>\n\n<p>La desigualdad en la vivienda representa una forma de desigualdad econ\u00f3mica en la que los individuos no tienen las mismas oportunidades de vivir en entornos seguros, libres de da\u00f1os, amenazas u obst\u00e1culos que impidan su prosperidad. La escalada del coste de la vida, agravada por los efectos de la pandemia del COVID-19, ha exacerbado la inseguridad de la vivienda para millones de personas. Una <a href=\"https:\/\/endhomelessness.org\/resource\/housing-insecurity-rent-relief-eviction-assistance\/\">encuesta nacional realizada en agosto de 2021<\/a> revel\u00f3 que 3,7 millones de encuestados indicaron que era \u00abmuy probable\u00bb o \u00abalgo probable\u00bb que fueran desahuciados en los dos meses siguientes. Adem\u00e1s, 7,7 millones de personas se declararon morosas en el pago del alquiler. Antes de la pandemia, la inseguridad en la vivienda estaba muy extendida entre muchos estadounidenses.<\/p>\n\n<p>Los datos de una <a href=\"https:\/\/health.gov\/healthypeople\/priority-areas\/social-determinants-health\/literature-summaries\/housing-instability#cit7\">encuesta de 2019<\/a> mostraban que 37,1 millones de hogares (tanto arrendatarios como propietarios) estaban identificados como<a href=\"https:\/\/nlihc.org\/gap\/about#:~:text=Cost%20burdens%20are%20a%20direct,its%20income%20on%20these%20expenses.\">\u00absobrecargados de gastos\u00bb<\/a>, lo que significa que dedicaban m\u00e1s del 30% de sus ingresos a gastos de vivienda. Entre ellos, 17,6 millones de hogares se consideraban gravemente sobrecargados, destinando m\u00e1s del 50% de sus ingresos a la vivienda. Quienes destinan <a href=\"https:\/\/journals.sagepub.com\/doi\/10.1177\/0192513X14530970\">el 30% o m\u00e1s de sus ingresos<\/a> a los gastos de vivienda tienen unos recursos mensuales m\u00ednimos para otras necesidades esenciales como alimentos, ropa, servicios p\u00fablicos y atenci\u00f3n sanitaria.<\/p>\n\n<p><strong>\u00bfQu\u00e9 constituye la inseguridad en la vivienda y c\u00f3mo la experimentan las personas?<\/strong><\/p>\n\n<p>La idea de que la inseguridad en la vivienda equivale \u00fanicamente a la falta de hogar es un concepto err\u00f3neo que tienen muchas personas. La realidad de la inseguridad en la vivienda abarca un amplio espectro de cuestiones:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>La lucha por encontrar y mantener una vivienda asequible y segura<\/li>\n\n\n\n<li>Enfrentarse constantemente al riesgo de desahucio<\/li>\n\n\n\n<li>Recurrir a alojamientos temporales como hoteles, albergues o couch-surfing<\/li>\n\n\n\n<li>La presi\u00f3n financiera para pagar el alquiler o los servicios p\u00fablicos<\/li>\n\n\n\n<li>Dependencia del cr\u00e9dito para gastos esenciales de vivienda<\/li>\n\n\n\n<li>Sentirse atrapado en condiciones de vida inseguras debido a alternativas limitadas<\/li>\n\n\n\n<li>La consecuencia \u00faltima de perder el hogar o la residencia<\/li>\n<\/ul>\n\n<p>Aunque la inseguridad en la vivienda puede afectar a cualquiera, <a href=\"https:\/\/health.gov\/healthypeople\/priority-areas\/social-determinants-health\/literature-summaries\/housing-instability\">tiene un impacto desproporcionado en los grupos marginados<\/a>, como las personas de clase trabajadora no blancas, las v\u00edctimas de violencia dom\u00e9stica, las personas discapacitadas, los j\u00f3venes que han estado en hogares de acogida, los miembros de la comunidad LGBTQIA+, las familias monoparentales, los inmigrantes, las personas con baja solvencia, los ex presidiarios, las personas con enfermedades cr\u00f3nicas y otras personas a las que las pr\u00e1cticas discriminatorias han marginado sistem\u00e1ticamente. Esta disparidad surge de sistemas e instituciones sociales que funcionan con prejuicios basados en estas caracter\u00edsticas.<\/p>\n\n<p>Para muchos, basta un gasto imprevisto o una emergencia para caer en la inseguridad de vivienda. La pandemia COVID-19 ejemplific\u00f3 esta vulnerabilidad, cogiendo desprevenidas a numerosas personas y provocando problemas de alojamiento imprevistos. Las consecuencias econ\u00f3micas de la p\u00e9rdida de empleos durante la pandemia <a href=\"https:\/\/www.nsvrc.org\/blogs\/why-housing-matters-sexual-assault-survivors\">obligaron a algunas supervivientes a situaciones<\/a> en las que se sent\u00edan obligadas a intercambiar sexo por necesidades o a seguir viviendo con sus agresores. M\u00e1s all\u00e1 del riesgo de violencia sexual, las personas se han enfrentado al hacinamiento, a la necesidad de mudarse con frecuencia y a las presiones del aburguesamiento. Adem\u00e1s, en la pandemia se dieron casos en que <a href=\"https:\/\/www.nbcnews.com\/news\/us-news\/landlords-are-targeting-vulnerable-tenants-solicit-sex-exchange-rent-advocates-n1186416?cid=sm_npd_nn_fb_ma\">los caseros explotaron la situaci\u00f3n<\/a> exigiendo sexo a las mujeres vulnerables como forma de pago del alquiler.<\/p>\n\n<p><strong>\u00bfC\u00f3mo afecta a las mujeres la inseguridad en la vivienda?<\/strong><\/p>\n\n<p>La inseguridad en la vivienda est\u00e1 profundamente entrelazada con cuestiones de racismo y normas de g\u00e9nero, y afecta m\u00e1s duramente a quienes est\u00e1n marginados tanto por la discriminaci\u00f3n racial como por la de g\u00e9nero. Esta desigualdad polifac\u00e9tica se manifiesta de diversas formas, como pr\u00e1cticas de pr\u00e9stamo discriminatorias por parte de los bancos, acoso por parte de los propietarios, disparidades salariales y una mayor probabilidad de dependencia econ\u00f3mica derivada de la violencia dom\u00e9stica. La vivienda segura y asequible sigue estando fuera del alcance de muchos debido a estas barreras sist\u00e9micas y a la insuficiencia de las redes de seguridad social. Los casos de <a href=\"https:\/\/familyresourcesinc.org\/2019\/11\/why-youth-run-away\/\">violencia sexual pueden provocar el desplazamiento<\/a> de los hogares familiares, lo que afecta significativamente a las mujeres y a los antiguos j\u00f3venes en acogida. En cambio, el rechazo de las familias afecta de forma desproporcionada a las personas LGBTQ+, dificultando a menudo su capacidad para conseguir una vivienda estable.<\/p>\n\n<p>La <a href=\"https:\/\/www.aauw.org\/resources\/research\/simple-truth\/\">diferencia salarial entre hombres y mujeres<\/a> agrava estos problemas, ya que las mujeres, sobre todo las de color, ganan bastante menos que sus hom\u00f3logos masculinos por el mismo trabajo. Esta discrepancia se pone de manifiesto en los datos del National Women&#8217;s Law Center, que muestran que las mujeres, de media, <a href=\"https:\/\/nwlc.org\/wp-content\/uploads\/2021\/02\/Gender-and-Racial-Justice-in-Housing.pdf\">ganan 82 c\u00e9ntimos por cada d\u00f3lar que ganan los hombres<\/a>, con diferencias a\u00fan mayores para las mujeres de color. La sobrerrepresentaci\u00f3n de las mujeres en empleos con salarios bajos limita a\u00fan m\u00e1s sus opciones de vivienda y aumenta su vulnerabilidad a la discriminaci\u00f3n en los pr\u00e9stamos. Los estudios han demostrado que los hombres homosexuales y bisexuales ganan menos que los heterosexuales, y <a href=\"https:\/\/www.americanprogress.org\/article\/the-gay-and-transgender-wage-gap\/\">las mujeres transexuales se enfrentan a reducciones salariales sustanciales<\/a> tras la transici\u00f3n, lo que disminuye su capacidad econ\u00f3mica para conseguir una vivienda.<\/p>\n\n<p>Adem\u00e1s, las personas del espectro LGBTQ+ corren un mayor riesgo de sufrir violencia en situaciones de desamparo, y una <a href=\"https:\/\/www.nsvrc.org\/sites\/default\/files\/2020-12\/Whatarethelinks_Final508.pdf\">parte importante de las personas transexuales<\/a> sufren agresiones sexuales en los albergues. Estas terribles circunstancias a menudo atrapan a las v\u00edctimas en condiciones de vida inseguras, empleos explotadores o en la calle sin un refugio adecuado. El miedo a perder la custodia de los hijos puede paralizar a los padres solteros a la hora de buscar ayuda. Al mismo tiempo, el estr\u00e9s provocado por estas afecciones afecta considerablemente al bienestar f\u00edsico, mental y emocional.<\/p>\n\n<p><strong>\u00bfQu\u00e9 podemos hacer?<\/strong><\/p>\n\n<p>A medida que navegamos por las complejidades de la crisis de la vivienda en Estados Unidos, se hace evidente que esta cuesti\u00f3n est\u00e1 profundamente entretejida con el tejido de la desigualdad de g\u00e9nero y racial. La cruda realidad a la que se enfrentan las mujeres, sobre todo las de comunidades marginadas, subraya la urgente necesidad de una reforma integral y un apoyo espec\u00edfico. El impacto desproporcionado sobre las mujeres y las personas LGBTQ+ no s\u00f3lo cuestiona nuestras normas sociales, sino que tambi\u00e9n pone en tela de juicio la eficacia de nuestras actuales pol\u00edticas de vivienda y sistemas de apoyo.<\/p>\n\n<p>Por tanto, es imperativo que todos nosotros -responsables pol\u00edticos, l\u00edderes comunitarios, activistas y ciudadanos- aboguemos por soluciones de vivienda inclusivas y equitativas. Esto incluye impulsar reformas pol\u00edticas que aborden las causas profundas de la inseguridad en la vivienda, como la diferencia salarial entre hombres y mujeres, las pr\u00e1cticas discriminatorias en materia de pr\u00e9stamos y vivienda, y la falta de opciones de vivienda asequible. Tambi\u00e9n debemos trabajar para reforzar las redes de seguridad social y los sistemas de apoyo a las personas afectadas por la violencia dom\u00e9stica, la falta de vivienda y la discriminaci\u00f3n.<\/p>\n\n<p>Tu voz es crucial en esta lucha por la justicia en materia de vivienda. Comprom\u00e9tete con grupos locales y nacionales de defensa de la vivienda, apoya pol\u00edticas que promuevan pr\u00e1cticas de vivienda justa y sensibiliza sobre las dimensiones de g\u00e9nero de la inseguridad en la vivienda. Juntos podemos luchar por un futuro en el que todos puedan acceder a una vivienda segura, asequible y equitativa. Este derecho fundamental no debe verse comprometido por el sexo, la raza o la situaci\u00f3n socioecon\u00f3mica de cada uno. No seamos espectadores de esta crisis. Es hora de pasar a la acci\u00f3n, abogar por el cambio y apoyar iniciativas para desmantelar las barreras a la igualdad en materia de vivienda. El camino hacia la resoluci\u00f3n de la crisis de la vivienda es largo y est\u00e1 plagado de retos. Aun as\u00ed, podemos allanar el camino hacia una sociedad m\u00e1s justa e integradora con un esfuerzo colectivo y un compromiso inquebrantable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A medida que navegamos por las complejidades de la crisis de la vivienda en Estados Unidos, se hace evidente que esta cuesti\u00f3n est\u00e1 profundamente entretejida con el tejido de la desigualdad de g\u00e9nero y racial. La cruda realidad a la que se enfrentan las mujeres, sobre todo las de comunidades marginadas, subraya la urgente necesidad de una reforma integral y un apoyo espec\u00edfico.  <\/p>\n","protected":false},"author":9,"featured_media":7906,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","om_disable_all_campaigns":false,"footnotes":""},"categories":[580],"tags":[581],"class_list":["post-7921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alertas-de-accion","tag-defensa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La crisis de la vivienda en EE.UU. es una cuesti\u00f3n de mujeres - Ascentria Care Alliance<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La crisis de la vivienda en EE.UU. es una cuesti\u00f3n de mujeres\" \/>\n<meta property=\"og:description\" content=\"A medida que navegamos por las complejidades de la crisis de la vivienda en Estados Unidos, se hace evidente que esta cuesti\u00f3n est\u00e1 profundamente entretejida con el tejido de la desigualdad de g\u00e9nero y racial. La cruda realidad a la que se enfrentan las mujeres, sobre todo las de comunidades marginadas, subraya la urgente necesidad de una reforma integral y un apoyo espec\u00edfico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ascentria.org\/es\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\/\" \/>\n<meta property=\"og:site_name\" content=\"Ascentria Care Alliance\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-09T17:11:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-24T16:35:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ascentria.org\/wp-content\/uploads\/2024\/05\/Housing-Crisis.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Samantha Gauvain\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Samantha Gauvain\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\\\/\"},\"author\":{\"name\":\"Samantha Gauvain\",\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/#\\\/schema\\\/person\\\/1b081cb58a629d260219f4b30a6021fc\"},\"headline\":\"La crisis de la vivienda en EE.UU. es una cuesti\u00f3n de mujeres\",\"datePublished\":\"2024-05-09T17:11:45+00:00\",\"dateModified\":\"2024-06-24T16:35:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\\\/\"},\"wordCount\":1381,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ascentria.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Housing-Crisis.png\",\"keywords\":[\"Defensa\"],\"articleSection\":[\"Alertas de acci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ascentria.org\\\/es\\\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\\\/\",\"url\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\\\/\",\"name\":\"La crisis de la vivienda en EE.UU. es una cuesti\u00f3n de mujeres - Ascentria Care Alliance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ascentria.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Housing-Crisis.png\",\"datePublished\":\"2024-05-09T17:11:45+00:00\",\"dateModified\":\"2024-06-24T16:35:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ascentria.org\\\/es\\\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ascentria.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Housing-Crisis.png\",\"contentUrl\":\"https:\\\/\\\/www.ascentria.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Housing-Crisis.png\",\"width\":1200,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La crisis de la vivienda en EE.UU. es una cuesti\u00f3n de mujeres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/\",\"name\":\"Ascentria Care Alliance\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/#organization\",\"name\":\"Ascentria Care Alliance\",\"url\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ascentria.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/asc-logo-horiz-light.png\",\"contentUrl\":\"https:\\\/\\\/www.ascentria.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/asc-logo-horiz-light.png\",\"width\":1534,\"height\":424,\"caption\":\"Ascentria Care Alliance\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/#\\\/schema\\\/person\\\/1b081cb58a629d260219f4b30a6021fc\",\"name\":\"Samantha Gauvain\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcc27317000908bb722d84e297b5740ba2e12ec50a678d307b7c7f252dde1c8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcc27317000908bb722d84e297b5740ba2e12ec50a678d307b7c7f252dde1c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcc27317000908bb722d84e297b5740ba2e12ec50a678d307b7c7f252dde1c8?s=96&d=mm&r=g\",\"caption\":\"Samantha Gauvain\"},\"url\":\"https:\\\/\\\/www.ascentria.org\\\/es\\\/author\\\/sgauvain\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La crisis de la vivienda en EE.UU. es una cuesti\u00f3n de mujeres - Ascentria Care Alliance","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"La crisis de la vivienda en EE.UU. es una cuesti\u00f3n de mujeres","og_description":"A medida que navegamos por las complejidades de la crisis de la vivienda en Estados Unidos, se hace evidente que esta cuesti\u00f3n est\u00e1 profundamente entretejida con el tejido de la desigualdad de g\u00e9nero y racial. La cruda realidad a la que se enfrentan las mujeres, sobre todo las de comunidades marginadas, subraya la urgente necesidad de una reforma integral y un apoyo espec\u00edfico.","og_url":"https:\/\/www.ascentria.org\/es\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\/","og_site_name":"Ascentria Care Alliance","article_published_time":"2024-05-09T17:11:45+00:00","article_modified_time":"2024-06-24T16:35:13+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/www.ascentria.org\/wp-content\/uploads\/2024\/05\/Housing-Crisis.png","type":"image\/png"}],"author":"Samantha Gauvain","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Samantha Gauvain","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ascentria.org\/es\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\/#article","isPartOf":{"@id":"https:\/\/www.ascentria.org\/es\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\/"},"author":{"name":"Samantha Gauvain","@id":"https:\/\/www.ascentria.org\/es\/#\/schema\/person\/1b081cb58a629d260219f4b30a6021fc"},"headline":"La crisis de la vivienda en EE.UU. es una cuesti\u00f3n de mujeres","datePublished":"2024-05-09T17:11:45+00:00","dateModified":"2024-06-24T16:35:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ascentria.org\/es\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\/"},"wordCount":1381,"commentCount":0,"publisher":{"@id":"https:\/\/www.ascentria.org\/es\/#organization"},"image":{"@id":"https:\/\/www.ascentria.org\/es\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ascentria.org\/wp-content\/uploads\/2024\/05\/Housing-Crisis.png","keywords":["Defensa"],"articleSection":["Alertas de acci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ascentria.org\/es\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ascentria.org\/es\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\/","url":"https:\/\/www.ascentria.org\/es\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\/","name":"La crisis de la vivienda en EE.UU. es una cuesti\u00f3n de mujeres - Ascentria Care Alliance","isPartOf":{"@id":"https:\/\/www.ascentria.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ascentria.org\/es\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\/#primaryimage"},"image":{"@id":"https:\/\/www.ascentria.org\/es\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ascentria.org\/wp-content\/uploads\/2024\/05\/Housing-Crisis.png","datePublished":"2024-05-09T17:11:45+00:00","dateModified":"2024-06-24T16:35:13+00:00","breadcrumb":{"@id":"https:\/\/www.ascentria.org\/es\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ascentria.org\/es\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ascentria.org\/es\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\/#primaryimage","url":"https:\/\/www.ascentria.org\/wp-content\/uploads\/2024\/05\/Housing-Crisis.png","contentUrl":"https:\/\/www.ascentria.org\/wp-content\/uploads\/2024\/05\/Housing-Crisis.png","width":1200,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.ascentria.org\/es\/la-crisis-de-la-vivienda-en-ee-uu-es-una-cuestion-de-mujeres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ascentria.org\/es\/"},{"@type":"ListItem","position":2,"name":"La crisis de la vivienda en EE.UU. es una cuesti\u00f3n de mujeres"}]},{"@type":"WebSite","@id":"https:\/\/www.ascentria.org\/es\/#website","url":"https:\/\/www.ascentria.org\/es\/","name":"Ascentria Care Alliance","description":"","publisher":{"@id":"https:\/\/www.ascentria.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ascentria.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ascentria.org\/es\/#organization","name":"Ascentria Care Alliance","url":"https:\/\/www.ascentria.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ascentria.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.ascentria.org\/wp-content\/uploads\/2023\/11\/asc-logo-horiz-light.png","contentUrl":"https:\/\/www.ascentria.org\/wp-content\/uploads\/2023\/11\/asc-logo-horiz-light.png","width":1534,"height":424,"caption":"Ascentria Care Alliance"},"image":{"@id":"https:\/\/www.ascentria.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ascentria.org\/es\/#\/schema\/person\/1b081cb58a629d260219f4b30a6021fc","name":"Samantha Gauvain","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9dcc27317000908bb722d84e297b5740ba2e12ec50a678d307b7c7f252dde1c8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9dcc27317000908bb722d84e297b5740ba2e12ec50a678d307b7c7f252dde1c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9dcc27317000908bb722d84e297b5740ba2e12ec50a678d307b7c7f252dde1c8?s=96&d=mm&r=g","caption":"Samantha Gauvain"},"url":"https:\/\/www.ascentria.org\/es\/author\/sgauvain\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ascentria.org\/es\/wp-json\/wp\/v2\/posts\/7921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ascentria.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ascentria.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ascentria.org\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ascentria.org\/es\/wp-json\/wp\/v2\/comments?post=7921"}],"version-history":[{"count":0,"href":"https:\/\/www.ascentria.org\/es\/wp-json\/wp\/v2\/posts\/7921\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ascentria.org\/es\/wp-json\/wp\/v2\/media\/7906"}],"wp:attachment":[{"href":"https:\/\/www.ascentria.org\/es\/wp-json\/wp\/v2\/media?parent=7921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ascentria.org\/es\/wp-json\/wp\/v2\/categories?post=7921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ascentria.org\/es\/wp-json\/wp\/v2\/tags?post=7921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}